{"id":1028,"count":1,"description":"","link":"https:\/\/agroservis-proizvodnja.eu\/en\/tag\/heder-za-kamilicu\/","name":"heder za kamilicu","slug":"heder-za-kamilicu","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agroservis-proizvodnja.eu\/en\/wp-json\/wp\/v2\/tags\/1028"}],"collection":[{"href":"https:\/\/agroservis-proizvodnja.eu\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agroservis-proizvodnja.eu\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agroservis-proizvodnja.eu\/en\/wp-json\/wp\/v2\/posts?tags=1028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}